{"id":135493,"date":"2024-03-07T16:11:24","date_gmt":"2024-03-07T22:11:24","guid":{"rendered":"https:\/\/www.winonahealth.org\/?page_id=135493"},"modified":"2026-02-04T10:55:34","modified_gmt":"2026-02-04T16:55:34","slug":"telemedicina","status":"publish","type":"page","link":"https:\/\/www.winonahealth.org\/es\/services\/specialty-care\/telemedicine\/","title":{"rendered":"Telemedicina"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1260px;margin-left: calc(-5% \/ 2 );margin-right: calc(-5% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:2.375%;--awb-margin-bottom-large:30px;--awb-spacing-left-large:2.375%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:2.375%;--awb-spacing-left-medium:2.375%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:2.375%;--awb-spacing-left-small:2.375%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><h4>\u00a1Es como una visita a domicilio! Atenci\u00f3n sin ir a la cl\u00ednica.<\/h4>\n<h2>Visitas de video de telemedicina disponibles<\/h2>\n<\/div><div class=\"fusion-text fusion-text-2\"><p>Si necesita consultar con un profesional de la salud en Winona Health, la telemedicina le permite realizar la consulta sin tener que acudir a la cl\u00ednica. Puede hacerlo desde la comodidad de su hogar. Esto tambi\u00e9n le ahorra el tiempo de viajar al consultorio de su profesional. Para protegerse y proteger a los dem\u00e1s del COVID-19, Winona Health recomienda encarecidamente el uso de las consultas de telemedicina.<\/p>\n<p>Llame al consultorio de su proveedor para ver si esta es una opci\u00f3n para usted: <a href=\"tel:5074577648\">507.457.7648<\/a>.<\/p>\n<\/div><div class=\"accordian fusion-accordian\" style=\"--awb-border-size:1px;--awb-icon-size:20px;--awb-content-font-size:16px;--awb-icon-alignment:right;--awb-hover-color:var(--awb-color6);--awb-border-color:var(--awb-custom_color_7);--awb-background-color:var(--awb-color6);--awb-divider-color:var(--awb-custom_color_7);--awb-divider-hover-color:var(--awb-custom_color_7);--awb-icon-color:var(--awb-color3);--awb-title-color:var(--awb-color3);--awb-content-color:var(--awb-custom_color_6);--awb-icon-box-color:var(--awb-color3);--awb-toggle-hover-accent-color:var(--awb-color4);--awb-toggle-active-accent-color:var(--awb-color4);--awb-title-font-family:var(--awb-typography2-font-family);--awb-title-font-weight:var(--awb-typography2-font-weight);--awb-title-font-style:var(--awb-typography2-font-style);--awb-title-font-size:16px;--awb-title-letter-spacing:var(--awb-typography2-letter-spacing);--awb-title-line-height:1.6;--awb-content-font-family:var(--awb-typography4-font-family);--awb-content-font-weight:var(--awb-typography4-font-weight);--awb-content-font-style:var(--awb-typography4-font-style);\"><div class=\"panel-group fusion-toggle-icon-right fusion-toggle-icon-unboxed\" id=\"accordion-135493-1\"><div class=\"fusion-panel panel-default panel-6d3cbd1d7dec85cc7 fusion-toggle-has-divider\" style=\"--awb-title-color:var(--awb-color3);--awb-content-color:var(--awb-custom_color_6);\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_6d3cbd1d7dec85cc7\"><a aria-expanded=\"false\" aria-controls=\"6d3cbd1d7dec85cc7\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-135493-1\" data-target=\"#6d3cbd1d7dec85cc7\" href=\"#6d3cbd1d7dec85cc7\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">\u00bfQu\u00e9 es la telemedicina?<\/span><\/a><\/h4><\/div><div id=\"6d3cbd1d7dec85cc7\" class=\"panel-collapse collapse\" aria-labelledby=\"toggle_6d3cbd1d7dec85cc7\"><div class=\"panel-body toggle-content fusion-clearfix\">La telemedicina es una visita cara a cara con su proveedor de atenci\u00f3n m\u00e9dica mediante el uso de tecnolog\u00eda.<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-54bf77118b5c0184e fusion-toggle-has-divider\" style=\"--awb-title-color:var(--awb-color3);--awb-content-color:var(--awb-custom_color_6);\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_54bf77118b5c0184e\"><a aria-expanded=\"false\" aria-controls=\"54bf77118b5c0184e\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-135493-1\" data-target=\"#54bf77118b5c0184e\" href=\"#54bf77118b5c0184e\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">\u00bfQu\u00e9 requiere una visita de telemedicina?<\/span><\/a><\/h4><\/div><div id=\"54bf77118b5c0184e\" class=\"panel-collapse collapse\" aria-labelledby=\"toggle_54bf77118b5c0184e\"><div class=\"panel-body toggle-content fusion-clearfix\">Solo necesitas una conexi\u00f3n a internet estable y un smartphone, tableta o computadora con c\u00e1mara web, micr\u00f3fono y altavoces. Los navegadores recomendados son Safari, Firefox o Chrome. No necesitas crear una cuenta ni descargar nada.<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-6310cea264d7b25cc fusion-toggle-has-divider\" style=\"--awb-title-color:var(--awb-color3);--awb-content-color:var(--awb-custom_color_6);\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_6310cea264d7b25cc\"><a aria-expanded=\"false\" aria-controls=\"6310cea264d7b25cc\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-135493-1\" data-target=\"#6310cea264d7b25cc\" href=\"#6310cea264d7b25cc\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">\u00bfQu\u00e9 tipos de visitas pueden utilizar telemedicina?<\/span><\/a><\/h4><\/div><div id=\"6310cea264d7b25cc\" class=\"panel-collapse collapse\" aria-labelledby=\"toggle_6310cea264d7b25cc\"><div class=\"panel-body toggle-content fusion-clearfix\">La telemedicina se puede utilizar para diversas consultas, como el manejo de enfermedades cr\u00f3nicas, la educaci\u00f3n nutricional, el manejo de problemas de salud mental y las visitas de seguimiento para diversos tipos de procedimientos. La telemedicina es ideal para consultas que no requieren atenci\u00f3n directa.<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-ad7234f362b4a720b fusion-toggle-has-divider\" style=\"--awb-title-color:var(--awb-color3);--awb-content-color:var(--awb-custom_color_6);\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_ad7234f362b4a720b\"><a aria-expanded=\"false\" aria-controls=\"ad7234f362b4a720b\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-135493-1\" data-target=\"#ad7234f362b4a720b\" href=\"#ad7234f362b4a720b\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Si programo una visita de telemedicina en lugar de una visita en la cl\u00ednica, \u00bfqu\u00e9 debo esperar?<\/span><\/a><\/h4><\/div><div id=\"ad7234f362b4a720b\" class=\"panel-collapse collapse\" aria-labelledby=\"toggle_ad7234f362b4a720b\"><div class=\"panel-body toggle-content fusion-clearfix\">Antes de su cita de telemedicina programada, recibir\u00e1 un correo electr\u00f3nico con instrucciones para acceder a su consulta, junto con un enlace para conectarse a la videoconsulta con su proveedor. Tambi\u00e9n se le proporcionar\u00e1 un n\u00famero de tel\u00e9fono por si tiene alguna pregunta sobre la configuraci\u00f3n. Unos 10 minutos antes de su cita, aseg\u00farese de poder conectarse y de que su c\u00e1mara y micr\u00f3fono funcionen. Luego, haga clic en un enlace para ingresar a la &quot;sala de espera virtual de telemedicina&quot;. Su proveedor podr\u00e1 unirse a su consulta. Podr\u00e1n verse y escucharse mutuamente, y se sentir\u00e1n casi como si estuvieran en la misma habitaci\u00f3n.<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-8b2dc4748338773a3 fusion-toggle-has-divider\" style=\"--awb-title-color:var(--awb-color3);--awb-content-color:var(--awb-custom_color_6);\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_8b2dc4748338773a3\"><a aria-expanded=\"false\" aria-controls=\"8b2dc4748338773a3\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-135493-1\" data-target=\"#8b2dc4748338773a3\" href=\"#8b2dc4748338773a3\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">\u00bfQu\u00e9 pasa con el seguro?<\/span><\/a><\/h4><\/div><div id=\"8b2dc4748338773a3\" class=\"panel-collapse collapse\" aria-labelledby=\"toggle_8b2dc4748338773a3\"><div class=\"panel-body toggle-content fusion-clearfix\">Su seguro se facturar\u00e1 de la misma manera que si lo atendieran en la cl\u00ednica. Se aplican los copagos, coaseguros y deducibles habituales seg\u00fan su plan.<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":135257,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-135493","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/pages\/135493","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/comments?post=135493"}],"version-history":[{"count":4,"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/pages\/135493\/revisions"}],"predecessor-version":[{"id":167599,"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/pages\/135493\/revisions\/167599"}],"up":[{"embeddable":true,"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/pages\/135257"}],"wp:attachment":[{"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/media?parent=135493"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}