{"id":142756,"date":"2018-01-06T22:18:20","date_gmt":"2018-01-07T04:18:20","guid":{"rendered":"https:\/\/www.winonahealth.org\/2018\/01\/06\/influenza-clearing-up-the-confusion-2\/"},"modified":"2024-03-13T22:39:37","modified_gmt":"2024-03-14T03:39:37","slug":"gripe-aclarando-la-confusion-2","status":"publish","type":"post","link":"https:\/\/www.winonahealth.org\/es\/2018\/01\/06\/influenza-clearing-up-the-confusion-2\/","title":{"rendered":"Gripe: aclarando la confusi\u00f3n"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:calc( 1200px + 0px );margin-left: calc(-0px \/ 2 );margin-right: calc(-0px \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:0px;--awb-margin-bottom-large:30px;--awb-spacing-left-large:0px;--awb-width-medium:100%;--awb-spacing-right-medium:0px;--awb-spacing-left-medium:0px;--awb-width-small:100%;--awb-spacing-right-small:0px;--awb-spacing-left-small:0px;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><div id=\"attachment_40727\" style=\"width: 210px\" class=\"wp-caption alignright\"><img decoding=\"async\" aria-describedby=\"caption-attachment-40727\" class=\"wp-image-40727 size-full\" src=\"https:\/\/www.winonahealth.org\/wp-content\/uploads\/Brown_small_RGB-e1454963129197.jpg\" alt=\"\" width=\"200\" height=\"240\" title=\"\"><p id=\"caption-attachment-40727\" class=\"wp-caption-text\">Denver Brown, Pensilvania<\/p><\/div>\n<p>Por <a href=\"https:\/\/www.winonahealth.org\/es\/encontrar-un-proveedor\/details\/541\/\" target=\"_blank\" rel=\"noopener noreferrer\">Denver Brown, PA-C<\/a>Medicina Familiar de Winona Health<\/p>\n<p>Ha llegado esa \u00e9poca del a\u00f1o otra vez. Disfrutamos de las fiestas con amigos y familiares y, en el proceso, intercambiamos algunas enfermedades infecciosas no deseadas.<\/p>\n<p>La gripe es un tema com\u00fan pero a menudo confuso, por eso pens\u00e9 en abordar algunas de las preguntas y conceptos err\u00f3neos m\u00e1s comunes respecto a esta enfermedad.<\/p>\n<ol>\n<li>La gripe no es una &quot;gripe estomacal&quot;. Es un virus respiratorio que causa fiebre, dolores corporales, tos, dolor de garganta, dolor de cabeza y fatiga. Los s\u00edntomas suelen ser graves y las personas sienten ganas de estar en cama todo el d\u00eda. Gastroenteritis es el t\u00e9rmino m\u00e9dico para lo que la mayor\u00eda de la gente llama &quot;gripe estomacal&quot;. Generalmente, las principales caracter\u00edsticas son v\u00f3mitos y diarrea. En la mayor\u00eda de los casos, se resuelve en uno o dos d\u00edas y, por lo general, no es peligrosa, salvo por la deshidrataci\u00f3n significativa que puede presentarse en algunos casos.<\/li>\n<li>\u201cLa vacuna contra la influenza no me ayud\u00f3 antes o me enferm\u00f3\u201d. Datos: La vacuna inyectable contra la influenza no contiene ning\u00fan virus \u201cvivo\u201d y no causa influenza. El aerosol nasal contra la influenza contiene un virus vivo pero debilitado y tiene la <em>posibilidad<\/em> Causar infecci\u00f3n, por lo que se limita a ciertos tipos de pacientes. La vacuna contra la gripe tampoco protege contra los virus del resfriado com\u00fan. La vacuna contra la gripe no protege contra la gripe estomacal, ya que son g\u00e9rmenes completamente diferentes.<\/li>\n<li>Mito: La influenza no es peligrosa. Realidad: La gravedad cambia cada a\u00f1o, pero seg\u00fan los CDC, la influenza causa entre 140,000 y 710,000 hospitalizaciones y entre 12,000 y 56,000 muertes al a\u00f1o desde 2010. Generalmente, las personas j\u00f3venes y sanas sin otras complicaciones no se enferman gravemente. Los ni\u00f1os peque\u00f1os (especialmente los menores de 2 a\u00f1os) y los adultos mayores de 65 a\u00f1os tienen mayor probabilidad de contraer una influenza grave, que a veces pone en peligro la vida. Tambi\u00e9n existen afecciones m\u00e9dicas que pueden aumentar el riesgo de contraer una infecci\u00f3n de influenza peligrosa, como el embarazo, las enfermedades card\u00edacas, el asma, la EPOC y la diabetes, por nombrar algunas.<\/li>\n<li>C\u00f3mo prevenir la infecci\u00f3n: La vacunaci\u00f3n contra la gripe es \u00fatil, pero su eficacia var\u00eda de un a\u00f1o a otro y no garantiza la protecci\u00f3n. Lavarse las manos con frecuencia y evitar el contacto con personas con gripe son buenas medidas de prevenci\u00f3n.<\/li>\n<li>\u00bfC\u00f3mo se trata la gripe? Para la mayor\u00eda de nosotros, simplemente quedarse en casa, descansar y usar medicamentos para aliviar los s\u00edntomas es totalmente adecuado. Si tiene riesgos de infecci\u00f3n grave como los mencionados anteriormente, deber\u00eda considerar consultar con un profesional de la salud para obtener un medicamento antiviral que pueda ayudar a disminuir la gravedad y la duraci\u00f3n de la enfermedad. El sitio web de los CDC (cdc.gov\/flu) ofrece una lista completa de indicaciones para la terapia antiviral. Es importante tener en cuenta que el tratamiento generalmente solo es efectivo si se inicia en las primeras 48 horas de la enfermedad, por lo que no se debe esperar si est\u00e1 indicado.<\/li>\n<\/ol>\n<p>As\u00ed que, \u00a1un brindis por la salud, por una mayor concienciaci\u00f3n sobre la gripe y por un a\u00f1o de estar libres de ella!<\/p>\n<\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":134030,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[124,125,161,1,154],"tags":[],"class_list":["post-142756","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-clinical","category-health","category-news","category-winona-health-community-news"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/posts\/142756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/comments?post=142756"}],"version-history":[{"count":3,"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/posts\/142756\/revisions"}],"predecessor-version":[{"id":153732,"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/posts\/142756\/revisions\/153732"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/media\/134030"}],"wp:attachment":[{"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/media?parent=142756"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/categories?post=142756"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/tags?post=142756"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}