{"id":143050,"date":"2020-06-05T20:38:16","date_gmt":"2020-06-06T01:38:16","guid":{"rendered":"https:\/\/www.winonahealth.org\/2020\/06\/05\/a-message-from-winona-area-residential-facility-leaders\/"},"modified":"2024-03-13T22:41:02","modified_gmt":"2024-03-14T03:41:02","slug":"un-mensaje-de-los-lideres-de-las-instalaciones-residenciales-del-area-de-winona","status":"publish","type":"post","link":"https:\/\/www.winonahealth.org\/es\/2020\/06\/05\/a-message-from-winona-area-residential-facility-leaders\/","title":{"rendered":"Un mensaje de los l\u00edderes de las instalaciones residenciales del \u00e1rea de Winona"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1260px;margin-left: calc(-5% \/ 2 );margin-right: calc(-5% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_3_4 3_4 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:75%;--awb-margin-top-large:0px;--awb-spacing-right-large:3.8%;--awb-margin-bottom-large:30px;--awb-spacing-left-large:3.1666666666667%;--awb-width-medium:100%;--awb-spacing-right-medium:2.375%;--awb-spacing-left-medium:2.375%;--awb-width-small:100%;--awb-spacing-right-small:2.375%;--awb-spacing-left-small:2.375%;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p>A medida que el estado de Minnesota inicia su reapertura gradual, y la ciudad de Winona sigue el ejemplo, nos gustar\u00eda brindar informaci\u00f3n y presentar una solicitud con respecto a las visitas a nuestros centros residenciales regionales, incluyendo residencias de ancianos, centros de vida asistida, hogares grupales y cualquier otro tipo de centro de vivienda colectiva. El n\u00famero de personas que dan positivo por COVID-19 en todo el pa\u00eds y en Minnesota no se ha estabilizado ni disminuido, y contin\u00faa habiendo un n\u00famero diario de muertes. De hecho, se estima que 27% de las muertes por COVID-19 a nivel nacional ocurrieron en residencias de ancianos. En Minnesota, sabemos que 80% de las muertes ocurrieron en residencias de ancianos. Todos conocemos las vulnerabilidades de estas poblaciones. Por esta raz\u00f3n, los l\u00edderes de nuestros centros residenciales de la zona desean compartir con ustedes los planes para las restricciones de visitas vigentes, as\u00ed como las opciones y expectativas para flexibilizar estas restricciones. Con base en la experiencia de la COVID-19 en EE. UU. y el impacto desproporcionado en las residencias para personas mayores, los Centros de Servicios de Medicare y Medicaid (CMS) publicaron criterios estrictos para los funcionarios estatales y locales, as\u00ed como para los directores de residencias de ancianos, al considerar la reapertura. Otras residencias podr\u00edan estar sujetas a estos mismos est\u00e1ndares ante la amenaza de la COVID-19. Es importante saber que el prop\u00f3sito de estos est\u00e1ndares es proteger a los residentes y al personal de contraer y propagar el virus. Tambi\u00e9n sabemos que existe una alta variabilidad de la COVID-19 entre comunidades, lo cual debe considerarse. Cuando la prevalencia es baja, el objetivo es mantenerla as\u00ed. Los factores que se incluyen en la toma de decisiones sobre la reapertura incluyen el estado de los casos positivos en la comunidad local, la dotaci\u00f3n de personal en estas instalaciones (la p\u00e9rdida de alg\u00fan paciente por cuarentena supone una carga para los recursos ya limitados), el acceso a las pruebas, el uso estricto de mascarillas, incluyendo a las visitas, la disponibilidad de EPI suficiente para el personal y la capacidad hospitalaria local. Tambi\u00e9n se recomienda que las instalaciones mantengan controles estrictos mientras la comunidad local y el estado contin\u00faan con sus planes de reapertura. En otras palabras, la reapertura de las residencias al p\u00fablico deber\u00eda retrasarse al menos 14 d\u00edas con respecto a otras. El Departamento de Salud de Minnesota est\u00e1 realizando encuestas de Prevenci\u00f3n y Control de Infecciones en todos los hogares de ancianos y hospitales del estado. Si bien todos estamos acostumbrados al proceso de encuesta, esta es una supervisi\u00f3n adicional para garantizar el cumplimiento de todas las pr\u00e1cticas requeridas. A medida que se han realizado las pruebas en nuestras instalaciones regionales, no hemos detectado ning\u00fan caso positivo. Esto demuestra la r\u00e1pida adopci\u00f3n y el cumplimiento de las pr\u00e1cticas de prevenci\u00f3n de infecciones, incluyendo las restricciones de visitas, en las residencias de Winona y sus alrededores. Sin embargo, estas restricciones tambi\u00e9n tienen un precio. Nuestra comunidad regional de Winona tiene la fortuna de contar con excelentes residencias que atienden a nuestros vecinos mayores y con discapacidad. El personal de nuestras instalaciones no reemplaza a la familia, pero s\u00ed se convierte en familia para los residentes. Durante la pandemia de COVID, esto se ha hecho a\u00fan m\u00e1s evidente. Facilitar llamadas de FaceTime, videollamadas, conversaciones a trav\u00e9s de la ventana, as\u00ed como brindar atenci\u00f3n personalizada en tiempos de aislamiento, es nuestro nuevo enfoque. Nuestro personal est\u00e1 encantado de hacerlo. La separaci\u00f3n de sus familias es una dificultad para nuestros residentes, y el personal est\u00e1 haciendo todo lo posible para cubrir esa necesidad. Todos esperamos con ansias el d\u00eda en que las familias puedan volver a las visitas presenciales con normalidad; \u00a1tambi\u00e9n los extra\u00f1amos a todos! Cuando esto ocurra, tengan en cuenta que se intensificar\u00e1n los controles antes de entrar a las instalaciones. El uso de mascarilla ser\u00e1 obligatorio, junto con la higiene de manos. No suspenderemos ninguna de las pr\u00e1cticas implementadas para proteger a los residentes, el personal ni las visitas. El distanciamiento social ya forma parte de nuestra vida diaria, y estamos buscando soluciones creativas para adaptarnos a esto y seguir manteniendo conexiones significativas. Entonces, \u00bfcu\u00e1ndo pueden venir a visitarnos? La respuesta probablemente no sea satisfactoria: &quot;depende&quot;. En este momento, debemos mantener est\u00e1ndares estrictos y mantener nuestras instalaciones libres de COVID. Las recientes reuniones masivas podr\u00edan aumentar los casos positivos en el estado y la propagaci\u00f3n. Estaremos atentos a esto. Sin duda, la atenci\u00f3n compasiva en situaciones terminales se tratar\u00e1 de forma diferente para que la familia pueda estar presente. Cada instalaci\u00f3n monitorear\u00e1 su propia situaci\u00f3n y aplicar\u00e1 su criterio para flexibilizar las restricciones de acuerdo con las directrices regulatorias. En general, compartimos nuestros planes y operamos de manera similar con respecto a estas regulaciones. Les pedimos paciencia, comprensi\u00f3n y apoyo. A cambio, le ofrecemos lo mismo. Todos usaremos nuestro mejor criterio para adaptarnos a los residentes y sus familias con el objetivo de mantener la seguridad de todos. Firmado. <em>L\u00edderes de instalaciones residenciales del \u00e1rea de Winona Maggie Modjeski, Sugarloaf Senior Living\/Bluffview Estates Linda Atkinson, Lake Winona Manor Cheryl Krage, Watkins Manor, Adith Miller y Roger Metz Manors Lynne Kern, Callista Court Carol Ehlinger, St. Anne of Winona Cheryl Nash, St. Anne of Winona Sara Blair, Sauer Health Care Amy Schroeder, Brookdale Senior Living Solutions Rebecca Sobolik, Brookdale Senior Living Solutions Shelly Stensgard, Good Shepard Lutheran Services Rachelle Schultz, Winona Health<\/em><\/p>\n<\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_4 1_4 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:25%;--awb-margin-top-large:0px;--awb-spacing-right-large:9.5%;--awb-margin-bottom-large:30px;--awb-spacing-left-large:3.8%;--awb-width-medium:100%;--awb-spacing-right-medium:2.375%;--awb-spacing-left-medium:2.375%;--awb-width-small:100%;--awb-spacing-right-small:2.375%;--awb-spacing-left-small:2.375%;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element\" style=\"text-align:center;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\"fusion-imageframe imageframe-none imageframe-1 hover-type-none\"><img decoding=\"async\" src=\"https:\/\/www.winonahealth.org\/wp-content\/uploads\/2018\/07\/Rachelle-Schultz_IMG5356-211x300.jpg\" class=\"img-responsive\" alt=\"\" title=\"\"><\/span><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:5px;margin-bottom:5px;width:100%;\"><\/div><div class=\"fusion-text fusion-text-2\">\n<p style=\"text-align: center;\"><em>Rachelle Schultz, EdD Presidenta\/Directora Ejecutiva<\/em><\/p>\n<\/div><div class=\"fusion-text fusion-text-3\"><p>A trav\u00e9s de esta columna digital, espero arrojar luz sobre lo que estamos trabajando tanto internamente como m\u00e1s all\u00e1 de nuestras paredes en colaboraci\u00f3n con otras organizaciones enfocadas en la comunidad.<\/p>\n<\/div><div ><a class=\"fusion-button button-flat button-medium button-default fusion-button-default button-1 fusion-button-default-span fusion-button-default-type\" style=\"--button_text_transform:none;\" target=\"_self\" href=\"\/es\/about-2\/que-esta-sucediendo\/\"><span class=\"fusion-button-text awb-button__text awb-button__text--default\">Volver a QU\u00c9 EST\u00c1 PASANDO<\/span><\/a><\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[124,1,128,154],"tags":[],"class_list":["post-143050","post","type-post","status-publish","format-standard","hentry","category-blog","category-news","category-whats-going-on-news","category-winona-health-community-news"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/posts\/143050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/comments?post=143050"}],"version-history":[{"count":2,"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/posts\/143050\/revisions"}],"predecessor-version":[{"id":153804,"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/posts\/143050\/revisions\/153804"}],"wp:attachment":[{"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/media?parent=143050"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/categories?post=143050"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/tags?post=143050"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}