{"id":143450,"date":"2021-08-18T14:14:02","date_gmt":"2021-08-18T19:14:02","guid":{"rendered":"https:\/\/www.winonahealth.org\/2021\/08\/18\/ben-adith-miller-classic-raises-200000-for-patient-care-fund\/"},"modified":"2024-03-13T22:42:35","modified_gmt":"2024-03-14T03:42:35","slug":"ben-adith-miller-classic-raises-200000-for-patient-care-fund","status":"publish","type":"post","link":"https:\/\/www.winonahealth.org\/es\/2021\/08\/18\/ben-adith-miller-classic-raises-200000-for-patient-care-fund\/","title":{"rendered":"Ben &amp; Adith Miller Classic recauda $200,000 para el Fondo de Atenci\u00f3n al Paciente"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1260px;margin-left: calc(-5% \/ 2 );margin-right: calc(-5% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:2.375%;--awb-margin-bottom-large:30px;--awb-spacing-left-large:2.375%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:2.375%;--awb-spacing-left-medium:2.375%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:2.375%;--awb-spacing-left-small:2.375%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p>El Cl\u00e1sico Ben &amp; Adith Miller 2021 de la Fundaci\u00f3n Winona Health recaud\u00f3 $200,000 para el Fondo de Atenci\u00f3n al Paciente Ben &amp; Adith Miller, un fondo ben\u00e9fico para personas y familias que reciben atenci\u00f3n m\u00e9dica en Winona Health. Este fue el 31.\u00ba aniversario del Cl\u00e1sico.  <div id=\"attachment_96550\" style=\"width: 310px\" class=\"wp-caption alignright\"><img decoding=\"async\" aria-describedby=\"caption-attachment-96550\" class=\"size-medium wp-image-96550\" src=\"https:\/\/www.winonahealth.org\/wp-content\/uploads\/DSC_2116-Lopez-Exhibition-web-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" title=\"\"><p id=\"caption-attachment-96550\" class=\"wp-caption-text\">La miembro del Sal\u00f3n de la Fama del Golf Mundial, Nancy L\u00f3pez, dio una demostraci\u00f3n, respondi\u00f3 preguntas y dio consejos durante una presentaci\u00f3n comunitaria el lunes por la ma\u00f1ana antes del torneo.<\/p><\/div>  El Cl\u00e1sico de Golf 2021 se celebr\u00f3 el lunes 9 de agosto en el Campo de Golf Cedar Valley e incluy\u00f3 un torneo de 18 hoyos y un scramble de 9 hoyos. Nancy L\u00f3pez, miembro del Sal\u00f3n de la Fama del Golf Mundial, ofreci\u00f3 una demostraci\u00f3n, respondi\u00f3 preguntas y ofreci\u00f3 consejos durante una presentaci\u00f3n comunitaria el lunes por la ma\u00f1ana a las 10, y luego convers\u00f3 y jug\u00f3 con los participantes durante toda la tarde. &quot;Para m\u00ed es importante formar parte de algo como esto y ayudar a los menos afortunados. Duermo mucho mejor sabiendo que estoy ayudando a mejorar la vida de los dem\u00e1s con causas como esta&quot;, declar\u00f3 L\u00f3pez durante la cena posterior al torneo. &quot;Me sent\u00ed muy bien recibida y la pas\u00e9 genial. Tienen una comunidad maravillosa. Sigan haciendo lo que est\u00e1n haciendo. Recordar\u00e9 a Winona y les contar\u00e9 a los dem\u00e1s lo maravillosa que es esta comunidad&quot;. Rebecca Lamberty, directora administrativa de Winona Health, agradeci\u00f3 a la familia Hugh y Vera Miller y a RTP Company por su continuo apoyo a Winona Health, al Fondo de Atenci\u00f3n al Paciente Ben &amp; Adith Miller y al Cl\u00e1sico Ben &amp; Adith Miller. &quot;Todos merecen acceso a servicios de salud de excelencia&quot;, afirm\u00f3. \u201cEl Fondo de Atenci\u00f3n al Paciente Ben &amp; Adith Miller ayuda a garantizar que todos tengan acceso a ese servicio\u201d.  <\/p>\n<blockquote><p>He sido autosuficiente, viviendo solo y trabajando hasta la llegada de la COVID. Mis horas se redujeron. No ten\u00eda seguro m\u00e9dico. Tuve que mudarme con mi familia. Este fondo de atenci\u00f3n al paciente me ayud\u00f3 m\u00e1s que solo econ\u00f3micamente. El apoyo en momentos de necesidad me ayud\u00f3 emocional y mentalmente. Me dio esperanza para seguir adelante. Estoy m\u00e1s agradecido de lo que puedo expresar con palabras. Espero que alg\u00fan d\u00eda pueda hacer lo mismo por los dem\u00e1s. \u2014 Beneficiario del Fondo de Atenci\u00f3n al Paciente<\/p><\/blockquote>\n<p>  M\u00e1s de 40 voluntarios de Winona Health estuvieron disponibles para ayudar con las tareas de los hoyos, los carritos de refrigerios, la correspondencia, las bolsas de regalos y una amplia variedad de tareas para que este evento se desarrollara sin problemas y los participantes tuvieran un d\u00eda excelente. El Fondo de Atenci\u00f3n al Paciente Ben &amp; Adith Miller fue fundado en 1986 por Benjamin A. Miller, ex empresario y fil\u00e1ntropo del \u00e1rea de Winona, en honor a su esposa, Adith, para ayudar a las personas y familias locales necesitadas a pagar la atenci\u00f3n m\u00e9dica en Winona Health. El Cl\u00e1sico de Golf anual comenz\u00f3 en 1990 como una recaudaci\u00f3n de fondos para ayudar a asegurar la financiaci\u00f3n continua de este recurso comunitario \u00fanico. Desde su creaci\u00f3n, el fondo ha ayudado a m\u00e1s de 6236 personas a pagar m\u00e1s de 13,2 millones de d\u00f3lares en gastos m\u00e9dicos de Winona Health. En el a\u00f1o fiscal 2020, el Fondo de Atenci\u00f3n al Paciente Ben &amp; Adith Miller otorg\u00f3 796.985 d\u00f3lares a 530 personas. El pr\u00f3ximo Ben &amp; Adith Miller Classic ser\u00e1 el lunes 8 de agosto de 2022. Para obtener m\u00e1s informaci\u00f3n o para contribuir al Fondo de atenci\u00f3n al paciente Ben &amp; Adith Miller, visite <a href=\"https:\/\/www.winonahealth.org\/es\/sobre-nosotros\/base\/\" target=\"_blank\" rel=\"noopener\">www.winonahealth.org\/fundaci\u00f3n<\/a>.<\/p>\n<\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":151512,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[445,124,126,1],"tags":[],"class_list":["post-143450","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bam-golf-classic","category-blog","category-foundation-news","category-news"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/posts\/143450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/comments?post=143450"}],"version-history":[{"count":3,"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/posts\/143450\/revisions"}],"predecessor-version":[{"id":153883,"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/posts\/143450\/revisions\/153883"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/media\/151512"}],"wp:attachment":[{"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/media?parent=143450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/categories?post=143450"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/tags?post=143450"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}