{"id":159681,"date":"2025-03-18T15:29:16","date_gmt":"2025-03-18T20:29:16","guid":{"rendered":"https:\/\/www.winonahealth.org\/2025\/03\/18\/student-athlete-logan-hickss-sewing-skills-add-smiles-to-surgery-center\/"},"modified":"2025-05-13T16:34:06","modified_gmt":"2025-05-13T21:34:06","slug":"-194","status":"publish","type":"post","link":"https:\/\/www.winonahealth.org\/es\/2025\/03\/18\/student-athlete-logan-hickss-sewing-skills-add-smiles-to-surgery-center\/","title":{"rendered":"Las habilidades de costura del estudiante atleta Logan Hicks suman sonrisas al Centro Quir\u00fargico"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1260px;margin-left: calc(-5% \/ 2 );margin-right: calc(-5% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_2_3 2_3 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:66.666666666667%;--awb-margin-top-large:0px;--awb-spacing-right-large:3.5625%;--awb-margin-bottom-large:30px;--awb-spacing-left-large:3.5625%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:2.375%;--awb-spacing-left-medium:2.375%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:2.375%;--awb-spacing-left-small:2.375%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p>No muchos jugadores de f\u00fatbol americano son tan h\u00e1biles con la m\u00e1quina de coser como en el campo. Conoce a Logan Hicks.<\/p>\n<p>Desde el quinto grado, Logan, ahora un estudiante atleta de 15 a\u00f1os en Cotter, ha estado haciendo fundas de almohadas c\u00f3modas y coloridas para personas que reciben cuidados paliativos junto con mantas y gorros quir\u00fargicos para ni\u00f1os y fundas para brazos para el Centro de Cirug\u00eda en Winona Health.<\/p>\n<p>Logan tuvo que someterse a algunas intervenciones quir\u00fargicas de ni\u00f1o, as\u00ed que conoce bien la experiencia. Ahora, con generosidad, retribuye a la comunidad brindando a ni\u00f1os y adultos un poco m\u00e1s de cuidado, consuelo y alegr\u00eda en momentos en que pueden sentirse ansiosos.<\/p>\n<p>\u201cPoder hacer cosas para otras personas necesitadas me llena de humildad\u201d, dijo. \u201cAdem\u00e1s, s\u00e9 que hay alguien al otro lado con una gran sonrisa, usando uno de mis sombreros o mantas\u201d.<\/p>\n<p>Logan dijo que una de las razones por las que disfruta de la costura, una habilidad que aprendi\u00f3 de su madre, es porque le permite hacer algo para beneficiar a otros en la comunidad. Se\u00f1al\u00f3 que la diversidad de art\u00edculos que fabrica tambi\u00e9n lo hace interesante y desafiante.<\/p>\n<p>El oto\u00f1o pasado, Logan se lesion\u00f3 durante la temporada de f\u00fatbol americano. Coser fue una de las cosas que m\u00e1s le atrajo durante su recuperaci\u00f3n. En febrero, entreg\u00f3 un gran lote de art\u00edculos nuevos que han deleitado a los cuidadores del Centro Quir\u00fargico y que sin duda alegrar\u00e1n a muchos pacientes y familias.<\/p>\n<p>Ahora completamente recuperado despu\u00e9s de recibir atenci\u00f3n del especialista en ortopedia Andrew Millis en Winona Health, Logan est\u00e1 feliz de estar de regreso en la sala de pesas prepar\u00e1ndose para la temporada de atletismo con sus compa\u00f1eros de equipo en Cotter.<\/p>\n<p>Adem\u00e1s de usar sus habilidades de costura al servicio de los dem\u00e1s, a Logan le gusta pescar con sus amigos, jugar al f\u00fatbol y hacer ejercicio. Le encantan las matem\u00e1ticas y aspira a ser ingeniero en el futuro.<\/p>\n<p>Reconocemos al cuidador de Logan y estamos agradecidos de tenerlo en nuestra comunidad. Somos Winona.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_3 1_3 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:33.333333333333%;--awb-margin-top-large:0px;--awb-spacing-right-large:7.125%;--awb-margin-bottom-large:30px;--awb-spacing-left-large:7.125%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:2.375%;--awb-spacing-left-medium:2.375%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:2.375%;--awb-spacing-left-small:2.375%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element\" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\"fusion-imageframe imageframe-none imageframe-1 hover-type-none\" style=\"border-radius:12px;\"><img decoding=\"async\" width=\"1000\" height=\"762\" title=\"Logan-Hicks-group-web\" src=\"https:\/\/www.winonahealth.org\/wp-content\/uploads\/Logan-Hicks-group-web.jpg\" class=\"img-responsive wp-image-159682\" alt=\"\"><\/span><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:10px;width:100%;\"><\/div><div class=\"fusion-text fusion-text-2\"><p style=\"font-size: 12px; line-height: 1.3;\">Logan Hicks entrega un lote de fundas de almohadas, gorros quir\u00fargicos para ni\u00f1os y fundas para brazos para personas que reciben cuidados paliativos junto con mantas para el Centro de Cirug\u00eda de Winona Health.<\/p>\n<\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":159682,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[124,1],"tags":[],"class_list":["post-159681","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-news"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/posts\/159681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/comments?post=159681"}],"version-history":[{"count":1,"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/posts\/159681\/revisions"}],"predecessor-version":[{"id":159870,"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/posts\/159681\/revisions\/159870"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/media\/159682"}],"wp:attachment":[{"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/media?parent=159681"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/categories?post=159681"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/tags?post=159681"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}