{"id":160876,"date":"2025-06-16T07:45:43","date_gmt":"2025-06-16T12:45:43","guid":{"rendered":"https:\/\/www.winonahealth.org\/?p=160876"},"modified":"2025-06-13T08:37:49","modified_gmt":"2025-06-13T13:37:49","slug":"los-examenes-de-nino-sano-pueden-incluir-examenes-fisicos-deportivos-3","status":"publish","type":"post","link":"https:\/\/www.winonahealth.org\/es\/2025\/06\/16\/well-child-exams-can-include-sports-physicals-3\/","title":{"rendered":"Los ex\u00e1menes de ni\u00f1o sano pueden incluir ex\u00e1menes f\u00edsicos deportivos."},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1260px;margin-left: calc(-5% \/ 2 );margin-right: calc(-5% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_2_3 2_3 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:66.666666666667%;--awb-margin-top-large:0px;--awb-spacing-right-large:3.5625%;--awb-margin-bottom-large:30px;--awb-spacing-left-large:3.5625%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:2.375%;--awb-spacing-left-medium:2.375%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:2.375%;--awb-spacing-left-small:2.375%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p>\u201cComo padre, entiendo lo r\u00e1pido que pasa el verano, as\u00ed que animamos a las familias a programar sus chequeos de bienestar infantil con anticipaci\u00f3n\u201d, dijo April Finucane, enfermera titulada y gerente de atenci\u00f3n primaria en Winona Health. \u201cAunque no est\u00e9n seguros sobre los deportes o actividades, es recomendable hacerse un examen f\u00edsico deportivo durante su chequeo de bienestar infantil regular. A menudo escuchamos que los padres de estudiantes de secundaria no sab\u00edan que era obligatorio para algunas actividades. Los ex\u00e1menes f\u00edsicos deportivos son necesarios a partir de s\u00e9ptimo grado, y algunos programas los solicitan desde los 10 a\u00f1os\u201d.<\/p>\n<p>La mayor\u00eda de los seguros m\u00e9dicos cubren los ex\u00e1menes de rutina para ni\u00f1os, y tambi\u00e9n se puede realizar un examen f\u00edsico deportivo en esa cita sin costo adicional. Si surgen ex\u00e1menes, vacunas o necesidades m\u00e9dicas adicionales, podr\u00edan aplicarse copagos.<\/p>\n<p>Es \u00fatil que los padres completen con antelaci\u00f3n su parte del formulario de reconocimiento f\u00edsico deportivo. Si necesita una copia de los formularios de reconocimiento f\u00edsico deportivo de su escuela, los formularios de reconocimiento f\u00edsico deportivo de Minnesota y Wisconsin est\u00e1n disponibles en l\u00ednea en <a href=\"https:\/\/www.winonahealth.org\/es\/atencion-primaria\/medicina-familiar\/examenes-fisicos-deportivos\/\" target=\"_blank\" rel=\"noopener\">winonahealth.org\/sportsphysicals<\/a>.<\/p>\n<p>Los chequeos de ni\u00f1o sano, incluidos los ex\u00e1menes f\u00edsicos deportivos, est\u00e1n disponibles en:<\/p>\n<ul>\n<li>Winona Health, 855 Mankato Ave., en Winona: 507.457.7607.<\/li>\n<li>Cl\u00ednica Rushford, 109 W. Jessie St., en Rushford: 507.864.7726.<\/li>\n<\/ul>\n<p>Para obtener m\u00e1s informaci\u00f3n sobre proveedores y servicios de atenci\u00f3n m\u00e9dica, visite nuestro <a href=\"https:\/\/www.winonahealth.org\/es\/encontrar-un-proveedor\/\">Encuentre un proveedor<\/a> p\u00e1gina.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_3 1_3 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:33.333333333333%;--awb-margin-top-large:0px;--awb-spacing-right-large:7.125%;--awb-margin-bottom-large:30px;--awb-spacing-left-large:7.125%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:2.375%;--awb-spacing-left-medium:2.375%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:2.375%;--awb-spacing-left-small:2.375%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element\" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\"fusion-imageframe imageframe-none imageframe-1 hover-type-none\" style=\"border-radius:12px;\"><img decoding=\"async\" width=\"1100\" height=\"739\" title=\"sitio web de bienestar infantil para ni\u00f1os\" src=\"https:\/\/www.winonahealth.org\/wp-content\/uploads\/2025\/05\/wellchild-3-kids_web.jpg\" class=\"img-responsive wp-image-160877\" srcset=\"https:\/\/www.winonahealth.org\/wp-content\/uploads\/2025\/05\/wellchild-3-kids_web-200x134.jpg 200w, https:\/\/www.winonahealth.org\/wp-content\/uploads\/2025\/05\/wellchild-3-kids_web-400x269.jpg 400w, https:\/\/www.winonahealth.org\/wp-content\/uploads\/2025\/05\/wellchild-3-kids_web-600x403.jpg 600w, https:\/\/www.winonahealth.org\/wp-content\/uploads\/2025\/05\/wellchild-3-kids_web-800x537.jpg 800w, https:\/\/www.winonahealth.org\/wp-content\/uploads\/2025\/05\/wellchild-3-kids_web.jpg 1100w\" sizes=\"(max-width: 1000px) 100vw, (max-width: 600px) 100vw, 400px\" alt=\"\"><\/span><\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":160877,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[124,125,1],"tags":[],"class_list":["post-160876","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-clinical","category-news"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/posts\/160876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/comments?post=160876"}],"version-history":[{"count":3,"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/posts\/160876\/revisions"}],"predecessor-version":[{"id":160902,"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/posts\/160876\/revisions\/160902"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/media\/160877"}],"wp:attachment":[{"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/media?parent=160876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/categories?post=160876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/tags?post=160876"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}