{"id":134705,"date":"2024-02-26T15:34:44","date_gmt":"2024-02-26T21:34:44","guid":{"rendered":"https:\/\/www.winonahealth.org\/?post_type=provider&#038;p=134705"},"modified":"2024-06-12T15:49:37","modified_gmt":"2024-06-12T20:49:37","slug":"duerr-katie","status":"publish","type":"provider","link":"https:\/\/www.winonahealth.org\/es\/providers\/duerr-katie\/","title":{"rendered":"Katie Duerr, enfermera certificada"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1260px;margin-left: calc(-5% \/ 2 );margin-right: calc(-5% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:2.375%;--awb-margin-bottom-large:30px;--awb-spacing-left-large:2.375%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:2.375%;--awb-spacing-left-medium:2.375%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:2.375%;--awb-spacing-left-small:2.375%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p>Se uni\u00f3 a Winona Health en 2018<\/p>\n<p><em>Sent\u00ed la vocaci\u00f3n de ser enfermera partera tras el nacimiento de mi tercer hijo, cuando mi enfermera partera me pidi\u00f3 que me inclinara y lo ayudara yo misma a nacer. Traer un hijo al mundo es un momento tan hermoso que te cambia la vida. La experiencia me abri\u00f3 los ojos a todas las personas que son necesarias para que ese momento suceda. Estuve muy agradecida por el cuidado de mi propia partera, y desde ese momento comenc\u00e9 a perseguir mi sue\u00f1o de poder ayudar a otras familias a contar sus propias y hermosas historias de parto. Como partera, mi pasi\u00f3n reside en ayudar a las mujeres en todas las etapas de la preconcepci\u00f3n, la concepci\u00f3n, el cuidado prenatal, el parto y el posparto, pero tambi\u00e9n me encanta poder brindar mis conocimientos y atenci\u00f3n a las mujeres en todas las etapas de la vida para que gocen de una salud integral \u00f3ptima. Mi filosof\u00eda de atenci\u00f3n siempre se ha centrado en escuchar primero. El camino hacia la salud de cada persona es \u00fanico y quiero asegurarme de comprender plenamente lo que sienten y experimentan mis pacientes para poder ofrecerles el mejor asesoramiento y la mejor atenci\u00f3n. Cada persona conoce mejor su cuerpo y sus experiencias, y mi objetivo siempre es asegurarme de que se sientan escuchados y respetados. Siempre que tengo tiempo libre, me gusta dedicarlo a trabajar en mi jard\u00edn, \u00a1lo que parece un trabajo de tiempo completo! Tambi\u00e9n disfruto de los crucigramas, el punto de cruz y relajarme viendo un poco de telerrealidad. Sin embargo, nada de eso es tan importante para m\u00ed como estar ah\u00ed para las personas a las que cuido.<\/em><\/p>\n<\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:30px;margin-bottom:30px;width:100%;\"><div class=\"fusion-separator-border sep-single sep-solid\" style=\"--awb-height:20px;--awb-amount:20px;border-color:var(--awb-custom_color_3);border-top-width:1px;\"><\/div><\/div><div class=\"fusion-text fusion-text-2\"><h4>Educaci\u00f3n:<\/h4>\n<ul>\n<li>Maestr\u00eda en Ciencias en Enfermer\u00eda Obst\u00e9trica, Frontier Nursing University, Hyden, Ky.<\/li>\n<li>Asociado en Ciencias en Enfermer\u00eda, Rochester Community and Technical College, Rochester, Minnesota.<\/li>\n<li>Licenciatura en Biolog\u00eda, Universidad Hamline, St. Paul, Minnesota.<\/li>\n<\/ul>\n<\/div><div ><a class=\"fusion-button button-flat button-medium button-default fusion-button-default button-1 fusion-button-default-span fusion-button-default-type\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/www.winonahealth.org\/es\/2018\/11\/05\/bienvenido-katie-duerr-enfermera-partera-certificada\/\"><span class=\"fusion-button-text awb-button__text awb-button__text--default\">Obtenga m\u00e1s informaci\u00f3n sobre Katie Duerr, CNM<\/span><\/a><\/div><\/div><\/div><\/div><\/div>","protected":false},"author":3,"featured_media":134706,"template":"","department":[88,93],"class_list":["post-134705","provider","type-provider","status-publish","has-post-thumbnail","hentry","department-primary-care","department-womens-health"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/provider\/134705","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/provider"}],"about":[{"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/types\/provider"}],"author":[{"embeddable":true,"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":3,"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/provider\/134705\/revisions"}],"predecessor-version":[{"id":134978,"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/provider\/134705\/revisions\/134978"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/media\/134706"}],"wp:attachment":[{"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/media?parent=134705"}],"wp:term":[{"taxonomy":"department","embeddable":true,"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/department?post=134705"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}