{"id":134852,"date":"2024-03-01T14:10:42","date_gmt":"2024-03-01T20:10:42","guid":{"rendered":"https:\/\/www.winonahealth.org\/?post_type=provider&#038;p=134852"},"modified":"2024-06-12T15:52:49","modified_gmt":"2024-06-12T20:52:49","slug":"lallaman-sarah-hace-faap","status":"publish","type":"provider","link":"https:\/\/www.winonahealth.org\/es\/providers\/lallaman-sarah-do-faap\/","title":{"rendered":"Sarah Lallaman, doctora en osteopat\u00eda, FAAP"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1260px;margin-left: calc(-5% \/ 2 );margin-right: calc(-5% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:2.375%;--awb-margin-bottom-large:30px;--awb-spacing-left-large:2.375%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:2.375%;--awb-spacing-left-medium:2.375%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:2.375%;--awb-spacing-left-small:2.375%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p>Se uni\u00f3 a Winona Health en 2011<\/p>\n<p><em>Cuando decid\u00ed dedicarme a la salud, enseguida me di cuenta de lo mucho que disfrutaba de la energ\u00eda l\u00fadica de los ni\u00f1os. Me llenan de energ\u00eda y es divertido jugar y cuidar a la vez. Me identifico con ellos y creo que ellos se llevan bien conmigo. Disfruto conociendo a padres y viendo crecer a sus beb\u00e9s en cada etapa de su desarrollo, hasta llegar a la adultez joven. Es fundamental que tu hijo pueda identificar a un m\u00e9dico que conozca y en quien pueda confiar cuando surjan problemas de salud importantes o graves, aunque, por supuesto, esperamos que nunca ocurran. Con mis propios hijos, s\u00e9 lo r\u00e1pido que pasa el tiempo y lo r\u00e1pido que crecen. En mi tiempo libre, disfruto del buceo, el voleibol, el s\u00f3ftbol, pasar tiempo en nuestro cobertizo para botes en el r\u00edo, hacer senderismo, pescar y disfrutar de una relajante noche de cine en familia.<\/em><\/p>\n<\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:30px;margin-bottom:30px;width:100%;\"><div class=\"fusion-separator-border sep-single sep-solid\" style=\"--awb-height:20px;--awb-amount:20px;border-color:var(--awb-custom_color_3);border-top-width:1px;\"><\/div><\/div><div class=\"fusion-text fusion-text-2\"><h4>T\u00edtulo de M\u00e9dico:<\/h4>\n<ul>\n<li>Universidad AT Still, Facultad de Medicina Osteop\u00e1tica Kirksville en Missouri<\/li>\n<\/ul>\n<h4>Residencia:<\/h4>\n<ul>\n<li>Hospitales y cl\u00ednicas universitarias en Columbia, Mo.<\/li>\n<\/ul>\n<h4>Certificaci\u00f3n de la Junta:<\/h4>\n<ul>\n<li>Junta Estadounidense de Pediatr\u00eda<\/li>\n<\/ul>\n<h4>Asociaciones profesionales:<\/h4>\n<ul>\n<li>Academia Estadounidense de Pediatr\u00eda<\/li>\n<\/ul>\n<h4>Notable:<\/h4>\n<ul>\n<li>Formaci\u00f3n adicional e inter\u00e9s en asma, autismo y salud mental\/conductual.<\/li>\n<li>Certificado en Reanimaci\u00f3n Neonatal (NRP)<\/li>\n<li>Certificado en Soporte Vital Avanzado Pedi\u00e1trico (PALS)<\/li>\n<li>Certificado STABLE (certificado para estabilizaci\u00f3n neonatal)<\/li>\n<\/ul>\n<\/div><div ><a class=\"fusion-button button-flat button-small button-default fusion-button-default button-1 fusion-button-default-span fusion-button-default-type\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/www.winonahealth.org\/es\/2011\/08\/05\/sarah-lallaman-do-se-une-winona-salud-personal-medico\/\"><span class=\"fusion-button-text awb-button__text awb-button__text--default\">Obtenga m\u00e1s informaci\u00f3n sobre Sarah Lallaman, DO<\/span><\/a><\/div><\/div><\/div><\/div><\/div>","protected":false},"author":3,"featured_media":134853,"template":"","department":[85,88],"class_list":["post-134852","provider","type-provider","status-publish","has-post-thumbnail","hentry","department-pediatrics-adolescent-medicine","department-primary-care"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/provider\/134852","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/provider"}],"about":[{"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/types\/provider"}],"author":[{"embeddable":true,"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":2,"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/provider\/134852\/revisions"}],"predecessor-version":[{"id":134855,"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/provider\/134852\/revisions\/134855"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/media\/134853"}],"wp:attachment":[{"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/media?parent=134852"}],"wp:term":[{"taxonomy":"department","embeddable":true,"href":"https:\/\/www.winonahealth.org\/es\/wp-json\/wp\/v2\/department?post=134852"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}